{"id":112506,"date":"2024-10-19T11:21:36","date_gmt":"2024-10-19T09:21:36","guid":{"rendered":"https:\/\/www.pandaclub.ch\/spiel-des-aal-lebens\/"},"modified":"2024-11-07T17:10:11","modified_gmt":"2024-11-07T16:10:11","slug":"gioco-anguilla","status":"publish","type":"page","link":"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/","title":{"rendered":"Il gioco del ciclo di vita dell&#8217;anguilla"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":116,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-112506","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gioco da tavolo - WWF - Panda Club<\/title>\n<meta name=\"description\" content=\"Costruisci un semplice gioco da tavola e scopri di pi\u00f9 sull&#039;incredibile viaggio delle anguille. Oppure inventa un nuovo gioco con altri animali e altre regole.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gioco da tavolo - WWF - Panda Club\" \/>\n<meta property=\"og:description\" content=\"Costruisci un semplice gioco da tavola e scopri di pi\u00f9 sull&#039;incredibile viaggio delle anguille. Oppure inventa un nuovo gioco con altri animali e altre regole.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/\" \/>\n<meta property=\"og:site_name\" content=\"WWF - Panda Club\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-07T16:10:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/\",\"url\":\"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/\",\"name\":\"Gioco da tavolo - WWF - Panda Club\",\"isPartOf\":{\"@id\":\"https:\/\/www.pandaclub.ch\/de\/#website\"},\"datePublished\":\"2024-10-19T09:21:36+00:00\",\"dateModified\":\"2024-11-07T16:10:11+00:00\",\"description\":\"Costruisci un semplice gioco da tavola e scopri di pi\u00f9 sull'incredibile viaggio delle anguille. Oppure inventa un nuovo gioco con altri animali e altre regole.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pandaclub.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il gioco del ciclo di vita dell&#8217;anguilla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pandaclub.ch\/de\/#website\",\"url\":\"https:\/\/www.pandaclub.ch\/de\/\",\"name\":\"WWF - Panda Club\",\"description\":\"Die Kinderwebseite des WWF Schweiz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pandaclub.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gioco da tavolo - WWF - Panda Club","description":"Costruisci un semplice gioco da tavola e scopri di pi\u00f9 sull'incredibile viaggio delle anguille. Oppure inventa un nuovo gioco con altri animali e altre regole.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/","og_locale":"it_IT","og_type":"article","og_title":"Gioco da tavolo - WWF - Panda Club","og_description":"Costruisci un semplice gioco da tavola e scopri di pi\u00f9 sull'incredibile viaggio delle anguille. Oppure inventa un nuovo gioco con altri animali e altre regole.","og_url":"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/","og_site_name":"WWF - Panda Club","article_modified_time":"2024-11-07T16:10:11+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/","url":"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/","name":"Gioco da tavolo - WWF - Panda Club","isPartOf":{"@id":"https:\/\/www.pandaclub.ch\/de\/#website"},"datePublished":"2024-10-19T09:21:36+00:00","dateModified":"2024-11-07T16:10:11+00:00","description":"Costruisci un semplice gioco da tavola e scopri di pi\u00f9 sull'incredibile viaggio delle anguille. Oppure inventa un nuovo gioco con altri animali e altre regole.","breadcrumb":{"@id":"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pandaclub.ch\/it\/gioco-anguilla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pandaclub.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Il gioco del ciclo di vita dell&#8217;anguilla"}]},{"@type":"WebSite","@id":"https:\/\/www.pandaclub.ch\/de\/#website","url":"https:\/\/www.pandaclub.ch\/de\/","name":"WWF - Panda Club","description":"Die Kinderwebseite des WWF Schweiz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pandaclub.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/pages\/112506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/comments?post=112506"}],"version-history":[{"count":8,"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/pages\/112506\/revisions"}],"predecessor-version":[{"id":113310,"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/pages\/112506\/revisions\/113310"}],"wp:attachment":[{"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/media?parent=112506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}