{"id":110073,"date":"2024-09-24T14:49:05","date_gmt":"2024-09-24T12:49:05","guid":{"rendered":"https:\/\/www.pandaclub.ch\/windlicht-aus-eis\/"},"modified":"2024-10-01T12:38:08","modified_gmt":"2024-10-01T10:38:08","slug":"lanterne-ghiaccio","status":"publish","type":"page","link":"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/","title":{"rendered":"Lanterne di ghiaccio"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":101,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-110073","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lanterne di ghiaccio - WWF - Panda Club<\/title>\n<meta name=\"description\" content=\"Una lanterna di ghiaccio per giornate fredde o per la notte di Natale. Un&#039;idea di bricolage per il sito internet per bambini del WWF Svizzera.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lanterne di ghiaccio - WWF - Panda Club\" \/>\n<meta property=\"og:description\" content=\"Una lanterna di ghiaccio per giornate fredde o per la notte di Natale. Un&#039;idea di bricolage per il sito internet per bambini del WWF Svizzera.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/\" \/>\n<meta property=\"og:site_name\" content=\"WWF - Panda Club\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-01T10:38:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/\",\"url\":\"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/\",\"name\":\"Lanterne di ghiaccio - WWF - Panda Club\",\"isPartOf\":{\"@id\":\"https:\/\/www.pandaclub.ch\/de\/#website\"},\"datePublished\":\"2024-09-24T12:49:05+00:00\",\"dateModified\":\"2024-10-01T10:38:08+00:00\",\"description\":\"Una lanterna di ghiaccio per giornate fredde o per la notte di Natale. Un'idea di bricolage per il sito internet per bambini del WWF Svizzera.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pandaclub.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lanterne di ghiaccio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pandaclub.ch\/de\/#website\",\"url\":\"https:\/\/www.pandaclub.ch\/de\/\",\"name\":\"WWF - Panda Club\",\"description\":\"Die Kinderwebseite des WWF Schweiz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pandaclub.ch\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lanterne di ghiaccio - WWF - Panda Club","description":"Una lanterna di ghiaccio per giornate fredde o per la notte di Natale. Un'idea di bricolage per il sito internet per bambini del WWF Svizzera.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/","og_locale":"it_IT","og_type":"article","og_title":"Lanterne di ghiaccio - WWF - Panda Club","og_description":"Una lanterna di ghiaccio per giornate fredde o per la notte di Natale. Un'idea di bricolage per il sito internet per bambini del WWF Svizzera.","og_url":"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/","og_site_name":"WWF - Panda Club","article_modified_time":"2024-10-01T10:38:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/","url":"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/","name":"Lanterne di ghiaccio - WWF - Panda Club","isPartOf":{"@id":"https:\/\/www.pandaclub.ch\/de\/#website"},"datePublished":"2024-09-24T12:49:05+00:00","dateModified":"2024-10-01T10:38:08+00:00","description":"Una lanterna di ghiaccio per giornate fredde o per la notte di Natale. Un'idea di bricolage per il sito internet per bambini del WWF Svizzera.","breadcrumb":{"@id":"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pandaclub.ch\/it\/lanterne-ghiaccio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pandaclub.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Lanterne di ghiaccio"}]},{"@type":"WebSite","@id":"https:\/\/www.pandaclub.ch\/de\/#website","url":"https:\/\/www.pandaclub.ch\/de\/","name":"WWF - Panda Club","description":"Die Kinderwebseite des WWF Schweiz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pandaclub.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/pages\/110073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/comments?post=110073"}],"version-history":[{"count":7,"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/pages\/110073\/revisions"}],"predecessor-version":[{"id":110430,"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/pages\/110073\/revisions\/110430"}],"wp:attachment":[{"href":"https:\/\/www.pandaclub.ch\/it\/wp-json\/wp\/v2\/media?parent=110073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}